{"id":4942,"date":"2023-04-05T10:30:52","date_gmt":"2023-04-05T08:30:52","guid":{"rendered":"https:\/\/mia-care.io\/?p=4942"},"modified":"2023-09-05T11:38:27","modified_gmt":"2023-09-05T09:38:27","slug":"centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana","status":"publish","type":"post","link":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/","title":{"rendered":"Centrali Operative Territoriali (COT): il futuro della sanit\u00e0 italiana"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u2019Italia ha l\u2019obiettivo di riformare il sistema sanitario nazionale, realizzando un <a href=\"https:\/\/www.pnrr.salute.gov.it\/portale\/pnrrsalute\/dettaglioContenutiPNRRSalute.jsp?lingua=italiano&amp;id=5828&amp;area=PNRR-Salute&amp;menu=comecambiassn\">modello di assistenza territoriale<\/a> che avvicini le persone e i loro bisogni di cura e prevenzione a strutture e operatori sanitari. Come? Grazie ai fondi stanziati dal PNRR che, una volta superata l\u2019emergenza pandemica, mira a razionalizzare ed efficientare il sistema sanitario nazionale.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A questo scopo sar\u00e0 adottata e attuata una <a href=\"https:\/\/www.pnrr.salute.gov.it\/portale\/pnrrsalute\/dettaglioContenutiPNRRSalute.jsp?lingua=italiano&amp;id=5898&amp;area=PNRR-Salute&amp;menu=riforme\">Riforma del modello organizzativo <\/a>della rete di assistenza territoriale basata:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>sul <strong>potenziamento dell\u2019assistenza domiciliare<\/strong>, anche grazie all\u2019impiego della telemedicina;<\/li>\n\n\n\n<li>sulla realizzazione di <strong>nuove strutture e presidi sanitar<\/strong>i sul territorio che migliorano l\u2019accessibilit\u00e0 e ampliano la disponibilit\u00e0 di servizi di prossimit\u00e0 ai cittadini;<\/li>\n\n\n\n<li>sulla definizione di un <strong>nuovo assetto istituzionale<\/strong> per la prevenzione sul territorio in ambito sanitario.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Cos&#8217;\u00e8 una Centrale Operativa Territoriale (COT)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La COT (Centrale Operativa Territoriale) viene definita come un <a href=\"https:\/\/www.agenas.gov.it\/images\/agenas\/In%20primo%20piano\/COT\/Lettura_digital_Quaderno_COT.pdf\">modello organizzativo <\/a>territoriale che ha come obiettivo quello di assicurare continuit\u00e0, accessibilit\u00e0 e integrazione della cura e dell\u2019assistenza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Questo nuovo soggetto avr\u00e0 il compito di sviluppare una strategia digitale e data-driven <\/strong>sui diversi percorsi di dimissione da ricoveri e soprattutto, di identificare i percorsi di cura pi\u00f9 adeguati, rispetto al profilo, clinico e sociale, del cittadino. Gli operatori delle COT dovranno infatti sviluppare anche competenze legate alla gestione di piattaforme di Telemedicina &#8211; telemonitoraggio e teleassistenza &#8211; <strong>promuovendo percorsi di prevenzione ed educazione sanitaria.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le COT avranno molteplici responsabilit\u00e0, con l\u2019obiettivo di essere il punto di contatto tra le diverse fasi del patient journey per assistiti che soffrono di patologie croniche o acute. Di seguito vengono definiti in modo lineare gli ambiti di azione:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Continuit\u00e0 assistenziale ospedali-territorio;<\/li>\n\n\n\n<li>Cure domiciliari e Cure palliative;<\/li>\n\n\n\n<li>Cronicit\u00e0\/Fragilit\u00e0 e Residenzialit\u00e0;<\/li>\n\n\n\n<li>Assistenza dell\u2019Infermiere di Famiglia e Comunit\u00e0;<\/li>\n\n\n\n<li>Assistenza Farmaceutica e Fornitura Protesica;<\/li>\n\n\n\n<li>Medicina Legale, Invalidit\u00e0 e Trasporti Sanitari.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Il ruolo del PNRR per sostenere la digitalizzazione delle cure di prossimit\u00e0<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Abilitare la creazione di strutture territoriali che siano basate su tecnologie digitali \u00e8 un percorso obbligato dall\u2019approccio \u201c<a href=\"https:\/\/www.iss.it\/one-health\">One Health<\/a>\u201d che si \u00e8 deciso di istituire al fine di innovare e ottimizzare l\u2019offerta di servizi di cura e assistenza. <strong>La cabina di regia del PNRR, insieme a Consip e Agenas, avr\u00e0 la missione di indirizzare al meglio i finanziamenti,<\/strong> evitando che si proceda in modo autonomo e frammentato ma definendo una strategia di trasformazione digitale comune.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Proprio per questa necessit\u00e0 di innovazione, legata anche a una responsabilit\u00e0 collettiva di migliorare la qualit\u00e0 delle cure erogate, i fondi del PNRR permetteranno lo sviluppo di<a href=\"https:\/\/www.pnrr.salute.gov.it\/portale\/pnrrsalute\/dettaglioContenutiPNRRSalute.jsp?lingua=italiano&amp;id=5875&amp;area=PNRR-Salute&amp;menu=investimenti\"> almeno 600 COT<\/a> in tutta Italia. L\u2019obiettivo \u00e8 prendere in carico le richieste dei cittadini e raccordarle con servizi e professionisti a disposizione, <strong>assicurando continuit\u00e0, accessibilit\u00e0 ed integrazione dell\u2019assistenza sanitaria e sociosanitaria.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le risorse a disposizione per questo impegnativo progetto sono 280 milioni di euro, ripartiti come segue:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>~ 103 milioni di euro per la <strong>realizzazione delle architetture digitali<\/strong> delle COT;<\/li>\n\n\n\n<li>~ 42 milioni di euro all&#8217;interoperabilit\u00e0<strong> <\/strong>tra le aziende sanitarie;<\/li>\n\n\n\n<li>~ 58 milioni di euro ai <strong>dispositivi (medici e tecnologici)<\/strong> a supporto degli operatori e dei pazienti;<\/li>\n\n\n\n<li>50 milioni di euro per i servizi di <strong>Intelligenza Artificiale <\/strong>a supporto dell\u2019assistenza primaria;<\/li>\n\n\n\n<li>~ 25 milioni di euro da destinare al potenziamento del <a href=\"https:\/\/www.portaletrasparenzaservizisanitari.it\/\">Portale della Trasparenza<\/a>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Perch\u00e8 le COT sono importanti per i cittadini e il sistema sanitario italiano<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Rafforzare le cure di prossimit\u00e0 e identificare il domicilio del paziente come il primo luogo in cui ricevere assistenza, rappresentano le strategie da intraprendere se si vuole puntare a erogare servizi sanitari puntuali, efficaci e preventivi.<br><br>Grazie alle tecnologie di ultima generazione, la creazione di centrali operative territoriali permetter\u00e0 innanzitutto di avere una <strong>torre di controllo e monitoraggio dei servizi attivi localmente<\/strong>. Soprattutto, per\u00f2, garantir\u00e0 la <strong>presa in carico di pazienti nel luogo pi\u00f9 adeguato,<\/strong> fornendo una visione chiara della storia clinica della persona, indipendentemente da dove sia stata curata precedentemente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infine, <strong>rendere finalmente interoperabili la documentazione clinica e i percorsi terapeutici <\/strong>significa elevare significativamente la qualit\u00e0 e l\u2019efficienza del lavoro degli operatori sanitari, che si sentiranno pi\u00f9 autonomi e sicuri nell\u2019erogare servizi di cura e assistenza. In particolare, le COT saranno predisposte per perseguire cinque principali obiettivi:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Coordinamento della presa in carico della persona;<\/li>\n\n\n\n<li>Ottimizzazione della rete assistenziale;<\/li>\n\n\n\n<li>Tracciamento e monitoraggio della transizione tra momenti di cura;<\/li>\n\n\n\n<li>Supporto informativo e logistico ai medici di medicina generale;<\/li>\n\n\n\n<li>Raccolta e monitoraggio dei percorsi integrati di cronicit\u00e0 dei pazienti in assistenza domiciliare.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">L\u2019Architettura cloud-native Target delle COT<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019implementazione dell\u2019infrastruttura informatica a supporto delle COT dovr\u00e0, a livello logico-funzionale, mettere a disposizione degli operatori presenti nelle COT i <a href=\"https:\/\/www.agenas.gov.it\/images\/agenas\/In%20primo%20piano\/COT\/Lettura_digital_Quaderno_COT.pdf\">seguenti strumenti<\/a>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>mappatura aggiornata di tutti i servizi della rete territoriale ed ospedaliera, completa di tutte le informazioni necessarie;<\/li>\n\n\n\n<li>funzionalit\u00e0 di accesso agli archivi di presa in carico che forniscono l\u2019informazione di quali servizi sanitari sono attivi;<\/li>\n\n\n\n<li>cruscotto di gestione e monitoraggio delle transizioni di setting assistenziale con informativa sullo stato e sulle caratteristiche delle stesse;<\/li>\n\n\n\n<li>sistema di ricezione e invio notifiche integrato con il cruscotto delle transizioni.<br><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019architettura target \u00e8 caratterizzata da un approccio event-driven orientato a massimizzare l\u2019interoperabilit\u00e0 tra i diversi interlocutori e sistemi. Dall\u2019immagine sottostante \u00e8 infatti possibile osservare come sia stato scelto lo standard <strong>HL7 FHIR per la creazione di uno strato di comunicazione e integrazione dati che abiliti lo scambio di informazioni tra le strutture sanitarie e le COT<\/strong>. Occorrer\u00e0 quindi creare un&#8217;architettura IT solida, scalabile ed efficiente a livello di prestazioni, che abiliti lo scambio di dati con i sistemi informatici dipartimentali e ospedalieri, alimentando e ricevendo dall\u2019Event Broker le informazioni provenienti dal business e dai sistemi legacy sottostanti.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/mia-care.io\/wp-content\/uploads\/2023\/04\/Screenshot-2023-04-05-100040.png?resize=495%2C348&#038;ssl=1\" alt=\"\" class=\"wp-image-3863\" style=\"width:495px;height:348px\" width=\"495\" height=\"348\" srcset=\"https:\/\/i0.wp.com\/mia-care.io\/wp-content\/uploads\/2023\/04\/Screenshot-2023-04-05-100040.png?w=990&amp;ssl=1 990w, https:\/\/i0.wp.com\/mia-care.io\/wp-content\/uploads\/2023\/04\/Screenshot-2023-04-05-100040.png?resize=300%2C211&amp;ssl=1 300w, https:\/\/i0.wp.com\/mia-care.io\/wp-content\/uploads\/2023\/04\/Screenshot-2023-04-05-100040.png?resize=768%2C540&amp;ssl=1 768w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:12px\">Source: <a href=\"https:\/\/www.agenas.gov.it\/comunicazione\/primo-piano\/2184-la-centrale-operativa-territoriale-dalla-realizzazione-all%E2%80%99attivazione\" target=\"_blank\" rel=\"noreferrer noopener\">Quaderno di Monitor<\/a> &#8220;La Centrale Operativa Territoriale: dalla realizzazione all\u2019attivazione&#8221; &#8211; Published by AGENAS, 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019utilizzo di tecnologie cloud-native per lo sviluppo di nuove applicazioni e architetture digitali \u00e8 una prerogativa fondamentale per costruire il <strong>concetto di \u201cprossimit\u00e0 territoriale\u201d, <\/strong>poich\u00e9 abilita l&#8217;interoperabilit\u00e0 dei dati sanitari tra diversi attori. Inoltre, permette di costruire soluzioni sostenibili nel tempo, facilmente evolvibili e in grado di scalare in modo rapido per poter sostenere il traffico elevato dovuto a un alto numero di utenti, garantendo loro un servizio affidabile e di qualit\u00e0.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusioni<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Laddove ai pazienti viene assicurata l\u2019assistenza pi\u00f9 adeguata<\/strong> a seconda della patologia e del territorio di riferimento, al sistema sanitario italiano viene garantita una sostenibilit\u00e0 su diversi fronti, da quello puramente economico a quello legato all\u2019esigenza di garantire equit\u00e0 di accesso alle cure nel corso degli anni.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mia-Care sta attualmente aiutando alcuni operatori ad indirizzare la creazione di architetture event-driven basate sulle moderne tecnologie cloud-native. Queste architetture permettono di creare delle COT che non siano solo centri di assistenza territoriale, ma che diventino anche detentori e garanti dei dati clinici condivisi dai pazienti grazie allo standard FHIR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mia-care.io\/it\/competence-center\/whitepaper-it\/abilita-servizi-digitali-basati-su-fhir-per-potenziare-linteroperabilita-dei-dati\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"200\" src=\"https:\/\/mia-care.io\/wp-content\/uploads\/2023\/07\/Paper_FHIR_Banner_ITA-1.svg\" alt=\"\" class=\"wp-image-4947\"\/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Italia ha l\u2019obiettivo di riformare il sistema sanitario nazionale, realizzando un modello di assistenza territoriale che avvicini le persone e [&hellip;]<\/p>\n","protected":false},"author":200466037,"featured_media":3880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","inline_featured_image":false,"description":"","form-header":"","hubspot":"","cta-link":"","cta-label":"Download","_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false},"categories":[688637399],"tags":[],"class_list":["post-4942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendenze-di-mercato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centrali Operative Territoriali: futuro della sanit\u00e0 italiana | Mia-Care<\/title>\n<meta name=\"description\" content=\"La COT viene definita come un modello organizzativo territoriale che vuole assicurare continuit\u00e0, accessibilit\u00e0 e integrazione della cure.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centrali Operative Territoriali: futuro della sanit\u00e0 italiana | Mia-Care\" \/>\n<meta property=\"og:description\" content=\"La COT viene definita come un modello organizzativo territoriale che vuole assicurare continuit\u00e0, accessibilit\u00e0 e integrazione della cure.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/\" \/>\n<meta property=\"og:site_name\" content=\"Mia-Care\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-05T08:30:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-05T09:38:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mia-care.io\/wp-content\/uploads\/2023\/04\/8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1188\" \/>\n\t<meta property=\"og:image:height\" content=\"792\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Dario Esposito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dario Esposito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/\"},\"author\":{\"name\":\"Dario Esposito\",\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/#\\\/schema\\\/person\\\/849b0bab57f3955c9d1801e7b252a8ae\"},\"headline\":\"Centrali Operative Territoriali (COT): il futuro della sanit\u00e0 italiana\",\"datePublished\":\"2023-04-05T08:30:52+00:00\",\"dateModified\":\"2023-09-05T09:38:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/\"},\"wordCount\":1112,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/mia-care.io\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/8.png?fit=1188%2C792&ssl=1\",\"articleSection\":[\"Tendenze di mercato\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/\",\"url\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/\",\"name\":\"Centrali Operative Territoriali: futuro della sanit\u00e0 italiana | Mia-Care\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/mia-care.io\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/8.png?fit=1188%2C792&ssl=1\",\"datePublished\":\"2023-04-05T08:30:52+00:00\",\"dateModified\":\"2023-09-05T09:38:27+00:00\",\"description\":\"La COT viene definita come un modello organizzativo territoriale che vuole assicurare continuit\u00e0, accessibilit\u00e0 e integrazione della cure.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/mia-care.io\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/8.png?fit=1188%2C792&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/mia-care.io\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/8.png?fit=1188%2C792&ssl=1\",\"width\":1188,\"height\":792},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/tendenze-di-mercato\\\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mia-care.io\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centrali Operative Territoriali (COT): il futuro della sanit\u00e0 italiana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/mia-care.io\\\/it\\\/\",\"name\":\"Mia-Care\",\"description\":\"Unlock the power of Digital Health\",\"publisher\":{\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mia-care.io\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/#organization\",\"name\":\"Mia-Care\",\"url\":\"https:\\\/\\\/mia-care.io\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mia-care.io\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/mia-care-logoA-color.png\",\"contentUrl\":\"https:\\\/\\\/mia-care.io\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/mia-care-logoA-color.png\",\"width\":1801,\"height\":791,\"caption\":\"Mia-Care\"},\"image\":{\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mia-care\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mia-care.io\\\/it\\\/#\\\/schema\\\/person\\\/849b0bab57f3955c9d1801e7b252a8ae\",\"name\":\"Dario Esposito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca91139e24531b7ef14b0b55029ecb2d8d7c76a4207ec741a2e98d91f1ed2f8f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca91139e24531b7ef14b0b55029ecb2d8d7c76a4207ec741a2e98d91f1ed2f8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ca91139e24531b7ef14b0b55029ecb2d8d7c76a4207ec741a2e98d91f1ed2f8f?s=96&d=mm&r=g\",\"caption\":\"Dario Esposito\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centrali Operative Territoriali: futuro della sanit\u00e0 italiana | Mia-Care","description":"La COT viene definita come un modello organizzativo territoriale che vuole assicurare continuit\u00e0, accessibilit\u00e0 e integrazione della cure.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/","og_locale":"it_IT","og_type":"article","og_title":"Centrali Operative Territoriali: futuro della sanit\u00e0 italiana | Mia-Care","og_description":"La COT viene definita come un modello organizzativo territoriale che vuole assicurare continuit\u00e0, accessibilit\u00e0 e integrazione della cure.","og_url":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/","og_site_name":"Mia-Care","article_published_time":"2023-04-05T08:30:52+00:00","article_modified_time":"2023-09-05T09:38:27+00:00","og_image":[{"width":1188,"height":792,"url":"https:\/\/mia-care.io\/wp-content\/uploads\/2023\/04\/8.png","type":"image\/png"}],"author":"Dario Esposito","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Dario Esposito","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/#article","isPartOf":{"@id":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/"},"author":{"name":"Dario Esposito","@id":"https:\/\/mia-care.io\/it\/#\/schema\/person\/849b0bab57f3955c9d1801e7b252a8ae"},"headline":"Centrali Operative Territoriali (COT): il futuro della sanit\u00e0 italiana","datePublished":"2023-04-05T08:30:52+00:00","dateModified":"2023-09-05T09:38:27+00:00","mainEntityOfPage":{"@id":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/"},"wordCount":1112,"commentCount":0,"publisher":{"@id":"https:\/\/mia-care.io\/it\/#organization"},"image":{"@id":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/mia-care.io\/wp-content\/uploads\/2023\/04\/8.png?fit=1188%2C792&ssl=1","articleSection":["Tendenze di mercato"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/","url":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/","name":"Centrali Operative Territoriali: futuro della sanit\u00e0 italiana | Mia-Care","isPartOf":{"@id":"https:\/\/mia-care.io\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/#primaryimage"},"image":{"@id":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/mia-care.io\/wp-content\/uploads\/2023\/04\/8.png?fit=1188%2C792&ssl=1","datePublished":"2023-04-05T08:30:52+00:00","dateModified":"2023-09-05T09:38:27+00:00","description":"La COT viene definita come un modello organizzativo territoriale che vuole assicurare continuit\u00e0, accessibilit\u00e0 e integrazione della cure.","breadcrumb":{"@id":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/#primaryimage","url":"https:\/\/i0.wp.com\/mia-care.io\/wp-content\/uploads\/2023\/04\/8.png?fit=1188%2C792&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mia-care.io\/wp-content\/uploads\/2023\/04\/8.png?fit=1188%2C792&ssl=1","width":1188,"height":792},{"@type":"BreadcrumbList","@id":"https:\/\/mia-care.io\/it\/tendenze-di-mercato\/centrali-operative-territoriali-cot-il-futuro-della-sanita-italiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mia-care.io\/it\/"},{"@type":"ListItem","position":2,"name":"Centrali Operative Territoriali (COT): il futuro della sanit\u00e0 italiana"}]},{"@type":"WebSite","@id":"https:\/\/mia-care.io\/it\/#website","url":"https:\/\/mia-care.io\/it\/","name":"Mia-Care","description":"Unlock the power of Digital Health","publisher":{"@id":"https:\/\/mia-care.io\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mia-care.io\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mia-care.io\/it\/#organization","name":"Mia-Care","url":"https:\/\/mia-care.io\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mia-care.io\/it\/#\/schema\/logo\/image\/","url":"https:\/\/mia-care.io\/wp-content\/uploads\/2021\/12\/mia-care-logoA-color.png","contentUrl":"https:\/\/mia-care.io\/wp-content\/uploads\/2021\/12\/mia-care-logoA-color.png","width":1801,"height":791,"caption":"Mia-Care"},"image":{"@id":"https:\/\/mia-care.io\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/mia-care\/"]},{"@type":"Person","@id":"https:\/\/mia-care.io\/it\/#\/schema\/person\/849b0bab57f3955c9d1801e7b252a8ae","name":"Dario Esposito","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ca91139e24531b7ef14b0b55029ecb2d8d7c76a4207ec741a2e98d91f1ed2f8f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ca91139e24531b7ef14b0b55029ecb2d8d7c76a4207ec741a2e98d91f1ed2f8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca91139e24531b7ef14b0b55029ecb2d8d7c76a4207ec741a2e98d91f1ed2f8f?s=96&d=mm&r=g","caption":"Dario Esposito"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/mia-care.io\/wp-content\/uploads\/2023\/04\/8.png?fit=1188%2C792&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcKZ9S-1hI","_links":{"self":[{"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/posts\/4942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/users\/200466037"}],"replies":[{"embeddable":true,"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/comments?post=4942"}],"version-history":[{"count":6,"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/posts\/4942\/revisions"}],"predecessor-version":[{"id":4950,"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/posts\/4942\/revisions\/4950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/media\/3880"}],"wp:attachment":[{"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/media?parent=4942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/categories?post=4942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mia-care.io\/it\/wp-json\/wp\/v2\/tags?post=4942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}